{"id":10438,"date":"2025-04-04T10:06:58","date_gmt":"2025-04-04T08:06:58","guid":{"rendered":"http:\/\/www.piustudio.it\/?page_id=10438"},"modified":"2025-04-04T10:10:35","modified_gmt":"2025-04-04T08:10:35","slug":"2024-2","status":"publish","type":"page","link":"http:\/\/www.piustudio.it\/en\/2024-2\/","title":{"rendered":"2024"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row_inner][vc_column_inner][vc_custom_heading text=&#8221;WORKS&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Riqualificazione edilizia e urbana per la creazione di un housing sociale. 228 appartamenti.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]via Amidani, Milano, MI[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Social housing[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Riqualificazione edilizia e urbana per la creazione di un housing sociale.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]via Medici del Vascello, Milano, MI[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Social housing[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Largo Tabacchi. Progettazione di un nuovo edificio residenziale.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]largo Tabacchi, Torino, TO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Residential[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Riqualificazione edilizia edificio residenziale.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]via Nizza 25, Torino, TO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Residential[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Relais Dal Cavaliere &#8211; Realizzazione di un B&amp;B di charme in un&#8217;antica cascina.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Castellino, Moncalvo, AT[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Hospitality[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Uffici Cogefa. Progettazione nuova sede uffici.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Corso Principe Eugenio, Torino, TO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Workspaces[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Colorado &#8211; Ristrutturazione piano sottotetto.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Castiglione Torinese, TO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Residential[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Concept architettonico per l&#8217;allestimento della corte dell&#8217;Antico Mercato di Ortigia.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Ortigia, Siracusa, SR[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Commercial[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Riqualificazione di un edificio residenziale.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Bologna, BO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Residential[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Restyling Gran Bar Torino.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Piazza Gran Madre di Dio, Torino, TO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Commercial[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Ampliamento Fondazione Paideia[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]via Santorre, Torino, TO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Workspaces[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Pianezza Hub, centro integrato per la famiglia.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Pianezza, TO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Workspaces[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Progettazione degli interni di un appartamento di nuova costruzione.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Rivoli, TO[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Residential[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Progetto di allestimento per 81 siti culturali siciliani.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Sicilia[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]Commercial[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row_inner][vc_column_inner][vc_custom_heading text=&#8221;WORKS&#8221; font_container=&#8221;tag:h4|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Riqualificazione edilizia e urbana per la creazione di un housing sociale. 228 appartamenti.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]via Amidani, Milano, MI[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Social housing[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Riqualificazione edilizia e urbana per la creazione di un housing sociale.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]via Medici del Vascello, Milano, MI[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Social housing[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_separator color=&#8221;black&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]Largo Tabacchi. Progettazione di un nuovo edificio residenziale.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]largo Tabacchi,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-10438","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.piustudio.it\/en\/wp-json\/wp\/v2\/pages\/10438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.piustudio.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.piustudio.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.piustudio.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.piustudio.it\/en\/wp-json\/wp\/v2\/comments?post=10438"}],"version-history":[{"count":4,"href":"http:\/\/www.piustudio.it\/en\/wp-json\/wp\/v2\/pages\/10438\/revisions"}],"predecessor-version":[{"id":10444,"href":"http:\/\/www.piustudio.it\/en\/wp-json\/wp\/v2\/pages\/10438\/revisions\/10444"}],"wp:attachment":[{"href":"http:\/\/www.piustudio.it\/en\/wp-json\/wp\/v2\/media?parent=10438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}